{"id":119332,"date":"2026-05-13T06:27:05","date_gmt":"2026-05-13T04:27:05","guid":{"rendered":"https:\/\/www.vorspeisenplatte.de\/speisen\/?p=119332"},"modified":"2026-05-13T06:27:05","modified_gmt":"2026-05-13T04:27:05","slug":"journal-dienstag-12-mai-2026-schoene-fuesse-ganz-kurz","status":"publish","type":"post","link":"https:\/\/www.vorspeisenplatte.de\/speisen\/2026\/05\/journal-dienstag-12-mai-2026-schoene-fuesse-ganz-kurz.htm","title":{"rendered":"Journal Dienstag, 12. Mai 2026 &#8211; Sch\u00f6ne F\u00fc\u00dfe, ganz kurz"},"content":{"rendered":"<p>Unwilliges Aufstehen, aber vor allem wegen der unerquicklichen Aussicht auf einen weiteren Arbeitstag. Drau\u00dfen regnerisch und d\u00fcster, ebenfalls kein Laune-Aufheller. Auf dem Marsch in die Arbeit stellte sich das Nieseln auch noch als kaltwindig heraus.<\/p>\n<p>Geordnetes Arbeiten, ich fand sogar Zeit f\u00fcr eine Online-Schulung &#8211; die sich als deutlich besser herausstellte als (wegen schlimmer Erfahrungen) bef\u00fcrchtet, ich hatte sogar Spa\u00df!<\/p>\n<p>M\u00f6glicherweise ist mein Zahnweh-Problem ins rechte Kiefergelenk gerutscht, das mich schmerzhaft an weitem \u00d6ffnen des Mundes hindert, noch sehen Sie mich am\u00fcsiert. Nach zwei unbeschwerten Tagen wollte Kauen wieder bedacht sein.<\/p>\n<p>Raus ins Westend auf einen Mittagscappuccino: Ich blieb zwar trocken, aber es war schei\u00dfkalt, Menschen trugen Winterjacken.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/260512_04_NottingHill.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-119344\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/260512_04_NottingHill.jpg\" alt=\"\" width=\"269\" height=\"473\" \/><\/a><\/p>\n<p>Sp\u00e4ter zu Mittag gab es eingeweichtes Muesli mit Joghurt und eine Birne.<\/p>\n<p>Anstrengender Arbeitsnachmittag, zumindest mit klarem Ende: Ich hatte einen Termin bei der Fu\u00dfkosmetikerin.<\/p>\n<p>Zu diesem marschierte ich noch mit warmen F\u00fc\u00dfen; f\u00fcr den Heimweg mit frisch lackierten Zehen hatte ich Sandalen dabei, um den Lack nicht gleich wieder zu ruinieren. Und so ging ich danach in ausgesprochen frischen Temperaturen \u00fcber Drogeriemarkteink\u00e4ufe in nackten F\u00fc\u00dfen heim. War gar nicht so schlimm.<\/p>\n<p>Den Lack am rechten gro\u00dfen Zehen ruinierte ich mir trotzdem: Eine Yogamatte, lassen Sie sich warnen, tut das bei Gymnastik\u00fcbungen auf allen vieren, die ein Abst\u00fctzen mit dem Fu\u00dfr\u00fccken erfordern (z.B. bei Katze-Kuh), recht gr\u00fcndlich. Zefix. Aber das eigentliche Pilates war super.<\/p>\n<p>Auf und um den Sessel in meinem Schlafzimmer begannen sich Kleidung und Dinge zu sammeln: Erste Pack-Schritte f\u00fcr meine Berlin-Reise ab Donnerstag.<\/p>\n<p>Der Ernteanteil hatte rote Zwiebeln gebracht, da denke ich immer automatisch an <a href=\"https:\/\/www.deliciousdays.com\/archives\/2010\/07\/24\/welcoming-dear-friends-flammkuchen-with-red-onions\/\" target=\"_blank\" rel=\"noopener\">Flammkuchen nach Nicky Stich<\/a>. Herr Kaltmamsell war so freundlich sie umzusetzen.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/260512_09_Nachtmahl.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-119345\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/260512_09_Nachtmahl.jpg\" alt=\"\" width=\"409\" height=\"362\" \/><\/a><\/p>\n<p>Sehr gut. Nachtisch Schokolade.<\/p>\n<p>Fr\u00fch ins Bett zum Lesen. Joachim Meyerhoffs <i>Alle Toten fliegen hoch: Amerika<\/i> liest sich schon gut, ist mir aber in vielen Passagen deutlich zu detailliert erz\u00e4hlt; es hat viel mehr von pers\u00f6nlichen Erinnerungen (bei denen man sich meist dar\u00fcber freut, wie viele Kleinigkeiten man noch von vor 30 Jahren wei\u00df und in denen die gut erz\u00e4hlte Geschichte weniger wichtig ist) als das sp\u00e4tere <i>Ach, diese L\u00fccke, diese entsetzliche L\u00fccke<\/i>.<\/p>\n<p>In mir arbeitete der k\u00fcrzlich geh\u00f6rte Bericht \u00fcber einen Arztbesuch: Der komplett unbekannte Herr Doktor hatte die erz\u00e4hlende Patientin geduzt, war auch mit &#8220;Der Peter kommt gleich&#8221; von seiner Mitarbeiterin angek\u00fcndigt worden. Das machte mir bewusst, wie gern ich sieze. Das deutsche Duzen\/Siezen wird ja manchmal zu Hierarchisierung erkl\u00e4rt: Wer sieze, erhebe sich bei Duzen \u00fcber das Gegen\u00fcber, Beweis Duzen von Kindern. Sollte das je mehrheitlich so empfunden werden, entschiede ich mich in Konsequenz f\u00fcr Durchsiezen. Ja, auch meine Eltern und meinen Partner, ja, auch den zweij\u00e4hrigen Kollegensohn. Den sogar ganz besonders gern. <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg09.met.vgwort.de\/na\/ede20cff0808482187eff42149b62d98\" alt=\"\" width=\"1\" height=\"1\" \/><\/p>\n<p>\u00a7<\/p>\n<p>Genau wie Claudia es beschreibt, ersehne ich die Zeit nach dem Erwerbsleben:<br \/>\n<a href=\"https:\/\/www.claudiakilian.de\/wertvolles\" target=\"_blank\" rel=\"noopener\">&#8220;Wertvolles&#8221;.<\/a> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg09.met.vgwort.de\/na\/ede20cff0808482187eff42149b62d98\" width=\"1\" height=\"1\" alt=\"\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unwilliges Aufstehen, aber vor allem wegen der unerquicklichen Aussicht auf einen weiteren Arbeitstag. Drau\u00dfen regnerisch und d\u00fcster, ebenfalls kein Laune-Aufheller. Auf dem Marsch in die Arbeit stellte sich das Nieseln auch noch als kaltwindig heraus. Geordnetes Arbeiten, ich fand sogar Zeit f\u00fcr eine Online-Schulung &#8211; die sich als deutlich besser herausstellte als (wegen schlimmer Erfahrungen) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,2,1],"tags":[],"class_list":["post-119332","post","type-post","status-publish","format-standard","hentry","category-bucher","category-fotos","category-general"],"_links":{"self":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/119332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/comments?post=119332"}],"version-history":[{"count":3,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/119332\/revisions"}],"predecessor-version":[{"id":119353,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/119332\/revisions\/119353"}],"wp:attachment":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/media?parent=119332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/categories?post=119332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/tags?post=119332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}