{"id":20873,"date":"2014-05-05T09:09:42","date_gmt":"2014-05-05T08:09:42","guid":{"rendered":"https:\/\/www.vorspeisenplatte.de\/speisen\/?p=20873"},"modified":"2014-05-06T06:38:59","modified_gmt":"2014-05-06T05:38:59","slug":"berlin-im-fruehling-2014-2","status":"publish","type":"post","link":"https:\/\/www.vorspeisenplatte.de\/speisen\/2014\/05\/berlin-im-fruehling-2014-2.htm","title":{"rendered":"Berlin im Fr\u00fchling 2014 &#8211; 2"},"content":{"rendered":"<p>Urlaub setzte gleich beim sonnt\u00e4glichen Aufwachen ein: Auf den Einsatz des Schwimmzeugs, dass bereits gepackt war, im <a href=\"http:\/\/www.berlinerbaeder.de\/118.html\" target=\"_blank\">Prinzenbad<\/a> hatte ich \u00fcberhaupt keine Lust, und das bevor ich auch nur den bew\u00f6lkten Himmel mit k\u00fchlem Wind bemerkt hatte. Ich verbrachte den Vormittag gem\u00fctlich \u00fcber Milchkaffee am Rechner und schrieb, wie Sie gemerkt haben. (Gest\u00e4ndnis: Ich habe diesmal meine kleine Cafetera und Espressopulver dabei, um nicht gleich f\u00fcr den Morgenkaffee das Haus verlassen zu m\u00fcssen.) Bis mich meine Verabredung um eins abholte, war auch noch Zeit f\u00fcr gem\u00fctliches Lesen. Da ich zum Flanieren verabredet war, trotzte ich der K\u00e4lte &#8211; wenigstens ein schwingender Rock sollte es f\u00fcr den Kudamm sein.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_Kleidung_2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_Kleidung_2.jpg\" alt=\"140504_Kleidung_2\" width=\"214\" height=\"369\" class=\"alignnone size-full wp-image-20876\" \/><\/a><\/p>\n<p>Zun\u00e4chst aber flanierten wir \u00fcber den alten Kreuzberger Friedhof.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_02_Kreuzberg_Friedhof.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_02_Kreuzberg_Friedhof.jpg\" alt=\"140504_02_Kreuzberg_Friedhof\" width=\"442\" height=\"494\" class=\"alignnone size-full wp-image-20878\" \/><\/a><\/p>\n<p>Ein Grabsteinfriedhof &#8211; war mir neu.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_07_Kreuzberg_Friedhof.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_07_Kreuzberg_Friedhof.jpg\" alt=\"140504_07_Kreuzberg_Friedhof\" width=\"555\" height=\"395\" class=\"alignnone size-full wp-image-20879\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_06_Kreuzberg_Friedhof.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_06_Kreuzberg_Friedhof.jpg\" alt=\"140504_06_Kreuzberg_Friedhof\" width=\"436\" height=\"406\" class=\"alignnone size-full wp-image-20880\" \/><\/a><\/p>\n<p>(Die Pointe des unteren Bilds w\u00e4re nat\u00fcrlich im Eimer gewesen, h\u00e4tte ich die Emailschildchen dar\u00fcber mitfotografiert: Schade lautet der Name der hier Bestatteten.)<\/p>\n<p>Die Flanage auf dem Kurf\u00fcrstendamm war im bitteren Wind nicht allzu ausf\u00fchrlich. Wir lie\u00dfen uns im wundersch\u00f6nen <a href=\"http:\/\/grosz-berlin.de\/kaffeehaus\/\" target=\"_blank\">Caf\u00e9 Grosz<\/a> nieder, ich a\u00df zum zweiten Fr\u00fchst\u00fcck ein St\u00fcck k\u00f6stliche Herrentorte und probierte die hausgemachte Limonade (sehr erfrischend, wenig s\u00fc\u00df). Am gestrigen Sonntag war auch das neue Kaufhaus <a href=\"https:\/\/www.bikiniberlin.de\/\" target=\"_blank\">Bikinihaus<\/a> ge\u00f6ffnet, ein weiterer angenehmer Schutz vor K\u00e4lte.<\/p>\n<p>F\u00fcr das Abendessen hatte meine Begleitung eine wunderbare Idee: Das <a href=\"http:\/\/www.restaurant-florian.de\/\" target=\"_blank\">Florian<\/a> beim Savignyplatz, eine Legende, zu der sie mir viele Geschichten erz\u00e4hlen konnte. Wir a\u00dfen sehr gut (ich hatte eine Artischocke mit zweierlei Dips als Vorspeise &#8211; Gescherze mit der Bedienung \u00fcber die Handhabung des Gerichts, knusprige Ente mit Klo\u00df als Hauptgang, sp\u00e4t noch Mascarponecreme mit Erdbeerrhabarber als Dessert), genossen Umgebung und ungemein freundliche Atmosph\u00e4re. Ich durfte Zeugin werden, wie meine Begleiterin eine servierende Dame (die Wirtin, wie ich mir sp\u00e4ter erkl\u00e4ren lie\u00df) mit &#8220;Sie kenne ich doch auch aus der Domina-Bar!&#8221; ansprach. Die Dame best\u00e4tigte lachend, es folgten weitere Berlin-Geschichten aus den 80ern, in denen meine Begleitung zumindest auf dem Papier als Kaltmamsell arbeitete.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_10_Florian.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/140504_10_Florian.jpg\" alt=\"140504_10_Florian\" width=\"397\" height=\"370\" class=\"alignnone size-full wp-image-20881\" \/><\/a><\/p>\n<p><i>Nachtrag 6. Mai 2014: <a href=\"http:\/\/gaga.twoday.net\/stories\/843565561\/\" target=\"_blank\">Gaga Nielsen hat unseren Ausflug mit mehr Details und Bildern beschrieben.<\/a><\/i> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ssl-vg03.met.vgwort.de\/na\/260de07812274e2791d0252057bc279d\" width=\"1\" height=\"1\" alt=\"\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Urlaub setzte gleich beim sonnt\u00e4glichen Aufwachen ein: Auf den Einsatz des Schwimmzeugs, dass bereits gepackt war, im Prinzenbad hatte ich \u00fcberhaupt keine Lust, und das bevor ich auch nur den bew\u00f6lkten Himmel mit k\u00fchlem Wind bemerkt hatte. Ich verbrachte den Vormittag gem\u00fctlich \u00fcber Milchkaffee am Rechner und schrieb, wie Sie gemerkt haben. (Gest\u00e4ndnis: Ich habe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,1],"tags":[],"class_list":["post-20873","post","type-post","status-publish","format-standard","hentry","category-fotos","category-general"],"_links":{"self":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/20873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/comments?post=20873"}],"version-history":[{"count":10,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/20873\/revisions"}],"predecessor-version":[{"id":20890,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/20873\/revisions\/20890"}],"wp:attachment":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/media?parent=20873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/categories?post=20873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/tags?post=20873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}