{"id":41715,"date":"2017-12-11T06:38:49","date_gmt":"2017-12-11T05:38:49","guid":{"rendered":"https:\/\/www.vorspeisenplatte.de\/speisen\/?p=41715"},"modified":"2017-12-11T06:44:38","modified_gmt":"2017-12-11T05:44:38","slug":"journal-samstag-sonntag-9-10-dezember-2017-ausflug-nach-basel","status":"publish","type":"post","link":"https:\/\/www.vorspeisenplatte.de\/speisen\/2017\/12\/journal-samstag-sonntag-9-10-dezember-2017-ausflug-nach-basel.htm","title":{"rendered":"Journal Samstag\/Sonntag, 9.\/10. Dezember 2017 &#8211; Ausflug nach Basel"},"content":{"rendered":"<p>Ich war auf eine Geburtstagsfeier eingeladen, also fuhr ich am Samstag nach bei Basel. F\u00fcr unerheblichen Aufpreis hatte ich mir eine Fahrt erster Klasse geg\u00f6nnt, ich sa\u00df bequem, freute mich an der Aussicht vor dem Fenster und am Zeitunglesen (neben der Wochenendausgabe der <i>S\u00fcddeutschen<\/i> einige wegen Dienstreise liegen gebliebene).<\/p>\n<p>Ein Aha war darin der Gastkommentar von Jeremy Adler \u00fcber die Verfassungsgeschichte Gro\u00dfbritanniens:<br \/>\n<a href=\"http:\/\/www.sueddeutsche.de\/politik\/gastkommentar-locker-undfrei-1.3783964\" rel=\"noopener\" target=\"_blank\">&#8220;Locker und frei&#8221;.<\/a><br \/>\nEbenfalls sehr erleuchtend fand ich die ganze Feuilletonseite \u00fcber Verschw\u00f6rungstheorien. Die Beschreibung der derzeit am meisten verbreiteten gibt es kostenlos online zu lesen:<br \/>\n<a href=\"http:\/\/www.sueddeutsche.de\/kultur\/acht-theorien-echsenmeister-1.3779181\" rel=\"noopener\" target=\"_blank\">&#8220;Ausgetauschte V\u00f6lker und Kinderpornos in der Pizzeria&#8221;.<\/a><br \/>\nDas hochinteressante Interview mit Michael Butter, Mitinitiator des EU-Projekts &#8220;Comparative Analysis of Conspiracy Theories&#8221; mit Forschenden aus 39 L\u00e4ndern, kostet leider Geld:<br \/>\n<a href=\"http:\/\/www.sueddeutsche.de\/kultur\/interview-mit-michael-butter-die-wirkung-von-verschwoerungstheorien-1.3778684?reduced=true\" rel=\"noopener\" target=\"_blank\">&#8220;Die Wirkung von Verschw\u00f6rungstheorien.&#8221;<\/a><\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171210_Tweet.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171210_Tweet.jpg\" alt=\"\" width=\"442\" height=\"90\" class=\"alignnone size-full wp-image-41732\" \/><\/a><\/p>\n<p>Dazwischen musste ich immer wieder auf mein Smartphone gucken, sehr phasziniert vom Umstand, dass mein Online-Ticket den Fahrtverlauf anzeigte:<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171209_01_Bahnreise.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171209_01_Bahnreise.jpg\" alt=\"\" width=\"288\" height=\"443\" class=\"alignnone size-full wp-image-41727\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171209_02_Bahnreise.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171209_02_Bahnreise.jpg\" alt=\"\" width=\"288\" height=\"442\" class=\"alignnone size-full wp-image-41728\" \/><\/a><\/p>\n<p>Beim Aussteigen entdeckte ich dann, welche gesponsorte Zuglekt\u00fcre ich verpasst hatte.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171209_07_Bahnfahrt.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171209_07_Bahnfahrt.jpg\" alt=\"\" width=\"423\" height=\"439\" class=\"alignnone size-full wp-image-41730\" \/><\/a><\/p>\n<p>Die Geburtstagsfeier genoss ich, a\u00df und trank k\u00f6stliche Dinge, lernte Menschen aus v\u00f6llig anderen Lebenswelten kennen &#8211; und freute mich arg, endlich mal <a href=\"http:\/\/bruellen.blogspot.de\/\" rel=\"noopener\" target=\"_blank\">Frau Br\u00fcllen<\/a> in Heimumgebung zu erleben.<\/p>\n<p>Ich \u00fcbernachtete in einer richtigen winzigen Dorfpension (extrem schlicht, aber sauber) an Gasthof. Sonntagmorgen machte ich mich nach Ausschlafen auf den R\u00fcckweg. Am Basler Bahnhof hatte ich noch gut Zeit f\u00fcr Morgenkaffee und trank gegen\u00fcber einen ausgezeichneten Cappuccino in der Confiserie Bachmann (ich mochte sehr, dass ich dabei an einer Theke sitzen konnte).<\/p>\n<p>Die R\u00fcckfahrt war dann ein wenig turbulenter, verursacht wohl durch das heftige Schneetreiben. Ich musste in Karlsruhe umsteigen, und der Zug dorthin hatte Versp\u00e4tung. Laut Durchsage des Schaffners w\u00fcrden wir den Anschlusszug verpassen, doch wie ein paar Mitreisende beschloss ich, die Minute zwischen Ankunft und Abfahrt f\u00fcr einen Sprintversuch durch die Unterf\u00fchrung zum Zielgleis zu nutzen: Mit Erfolg, wir kamen alle noch rein.<\/p>\n<p>Das anschlie\u00dfende Abenteuer habe ich f\u00fcrs Techniktagebuch aufgeschrieben:<br \/>\n<a href=\"https:\/\/techniktagebuch.tumblr.com\/post\/168396674497\/10-dezember-2017\" rel=\"noopener\" target=\"_blank\">&#8220;Besser reisen mit Schaltschrankschl\u00fcssel&#8221;.<\/a><\/p>\n<p>Der Protagonist:<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171210_05_Schaltschrankschluessel.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171210_05_Schaltschrankschluessel.jpg\" alt=\"\" width=\"393\" height=\"400\" class=\"alignnone size-full wp-image-41722\" \/><\/a><\/p>\n<p>Es dauerte alles ein wenig l\u00e4nger, doch wenn ich aus dem Zug ins Schneetreiben schaute und die Autos auf wei\u00dfen Stra\u00dfen sah, war ich doch sehr froh \u00fcber die Wahl meines Reisemittels: Warm und gesch\u00fctzt, mit sch\u00f6nem erh\u00f6hten Ausblick sowie Klo. Ich las mein Granta <i>Canada<\/i> aus (gut!).<\/p>\n<p>Kurz vor Eintreffen im regnerischen M\u00fcnchen erreichte mich die Nachricht des Herrn Kaltmamsell, dass meine Eltern zu einem \u00dcberraschungsbesuch da seien: Pl\u00e4tzchen\u00fcbergabe. Mich empfingen daheim also gleich mal liebe Eltern und Weihnachtspl\u00e4tzchen aus Mutters K\u00fcche, ich konnte den beiden den Stollen aus meiner Produktion mitgeben.<\/p>\n<p>Nachtmittags und abends Befremden \u00fcber das Gemotze und die Vorw\u00fcrfe bei Verkehrsbehinderungen durch Schnee: So ist das halt, wenn&#8217;s schneit! V\u00f6llig reibungslosen Verkehr gibt&#8217;s nur im wetterlosen Vakuum.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171210_Tweet_2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/171210_Tweet_2.jpg\" alt=\"\" width=\"497\" height=\"62\" class=\"alignnone size-full wp-image-41737\" \/><\/a> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ssl-vg03.met.vgwort.de\/na\/4ced2509eff041c6803d081de61b2a4d\" width=\"1\" height=\"1\" alt=\"\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich war auf eine Geburtstagsfeier eingeladen, also fuhr ich am Samstag nach bei Basel. F\u00fcr unerheblichen Aufpreis hatte ich mir eine Fahrt erster Klasse geg\u00f6nnt, ich sa\u00df bequem, freute mich an der Aussicht vor dem Fenster und am Zeitunglesen (neben der Wochenendausgabe der S\u00fcddeutschen einige wegen Dienstreise liegen gebliebene). Ein Aha war darin der Gastkommentar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,2,1],"tags":[],"class_list":["post-41715","post","type-post","status-publish","format-standard","hentry","category-essen","category-fotos","category-general"],"_links":{"self":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/41715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/comments?post=41715"}],"version-history":[{"count":3,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/41715\/revisions"}],"predecessor-version":[{"id":41743,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/41715\/revisions\/41743"}],"wp:attachment":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/media?parent=41715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/categories?post=41715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/tags?post=41715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}