{"id":82451,"date":"2022-12-07T06:11:39","date_gmt":"2022-12-07T05:11:39","guid":{"rendered":"https:\/\/www.vorspeisenplatte.de\/speisen\/?p=82451"},"modified":"2022-12-07T09:39:39","modified_gmt":"2022-12-07T08:39:39","slug":"journal-dienstag-6-dezember-2022-meine-nikolaus-geschenke","status":"publish","type":"post","link":"https:\/\/www.vorspeisenplatte.de\/speisen\/2022\/12\/journal-dienstag-6-dezember-2022-meine-nikolaus-geschenke.htm","title":{"rendered":"Journal Dienstag, 6. Dezember 2022 &#8211; Meine Nikolaus-Geschenke"},"content":{"rendered":"<p>1. Geschenk<br \/>\nAls ich Herrn Kaltmamsell am Montagmorgen bei Verlassen der Wohnung darauf hinwies, dass am Dienstag FEI Nikolaus sei, nannte er das &#8220;geradezu beleidigend&#8221;. Ich wollte lediglich ganz sicher gehen, dass sich gestern Morgen niemand w\u00fcrde gr\u00e4men m\u00fcssen, weil er vergessen hatte, mir einen Schokoladennikolaus vor die T\u00fcr zu stellen. Komplett gr\u00e4mungsfreier Morgen, zwei Schokoladennikol\u00e4use hatten vor den respektiven T\u00fcren p\u00fcnktlich ihren Auftritt.<\/p>\n<p>2. Geschenk<br \/>\nEinen seltenen Auftritt hatten Sterne am Himmel: Die Wolkendecke lichtete sich genug, dass ich beim Fensterschlie\u00dfen ihr Funkeln am morgentlichen Nachthimmel sah.<\/p>\n<p>3. Geschenk<br \/>\nMir selbst diesen irischen Tweedrock geschenkt:<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/221206_02_Kleidung.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/221206_02_Kleidung.jpg\" alt=\"\" width=\"205\" height=\"430\" class=\"alignnone size-full wp-image-82472\" \/><\/a><\/p>\n<p>Er ist eine Gr\u00f6\u00dfe zu gro\u00df &#8211; weil ich besonders sorgf\u00e4ltig war: Da ich den Hersteller noch nicht kannte, verlie\u00df ich mich nicht auf die vertraute Konfektionsgr\u00f6\u00dfe, sondern ma\u00df meine Taille aus und glich das Ergebnis mit der Tabelle des Anbieters ab. Sie ergab eine Konfektionsgr\u00f6\u00dfe h\u00f6her als sonst, sogar am oberen Ende. Leider passte das aus Irland gelieferte edle St\u00fcck trotzdem nicht (wozu dann diese Ma\u00dftabelle bitte?), meine gewohnte Gr\u00f6\u00dfe w\u00e4re richtig gewesen. Da es genau dieses Modell in dieser aber nicht mehr gibt und mir zudem der Umstand der R\u00fccksendung zu gro\u00df ist, behalte ich ihn. So kann ich halt auch einen dicken Wollpulli reinstecken. Und vielleicht lasse ich ihn ja irgendwann vom Schneider enger machen.<\/p>\n<p>4. Geschenk<br \/>\nAuf dem Weg in die Arbeit hatte ich einem Radler zu danken: Er rutsche gleich in der ersten Kurve meiner Route weg und legte sich flach: So musste ich nicht selbst durch einen Sturz herausfinden, dass es eisglatt war und trippelte vorsichtig ins B\u00fcro.<\/p>\n<p>Beim Auspacken merkte ich dort: Ich hatte statt meinem Butterbrot versehentlich das Restst\u00fcck spanischen Schafsk\u00e4se als Brotzeit aus dem K\u00fchlschrank gegriffen. Und mich beim \u00d6ffnen meines Rucksacks ein wenig \u00fcber den Stallgeruch gewundert.<\/p>\n<p>Der Morgenhimmel entwickelte sich zu Sonnenschein, der bis fast halb zehn erfreute. Dann R\u00fcckkehr zu Bleihimmel. (Um fair zu sein, blieb den ganzen Tag ein heller Streifen am Horizont &#8211; den die Sonne f\u00fcr einen sch\u00fcchternen Untergangs-Auftritt nutzte.)<\/p>\n<p>Zu Mittag also <i>kein<\/i> Pumpernickel, sondern zwei Brezen aus der Cafeteria, vorgeschnittene Orangen.<\/p>\n<p>Nachmittags schaffte ich sogar warme H\u00e4nde. Irgendwann lerne ich auch noch, dass &#8220;ah, dann kann ich die Heizung ja runterdrehen&#8221; keine gewinnbringende Reaktion darauf ist.<\/p>\n<p><a href=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/221206_05_Bueroblick.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vorspeisenplatte.de\/speisen\/archiv\/221206_05_Bueroblick.jpg\" alt=\"\" width=\"524\" height=\"382\" class=\"alignnone size-full wp-image-82473\" \/><\/a><\/p>\n<p>5. Geschenk<br \/>\nAuf dem Heimweg (kalt) sah ich auf der Theresienh\u00f6he vorm Tor der Villa Wagner ein M\u00e4uschen huschen. Ich blieb still stehen, da traute es sich vor. Und dann sah ich ein paar Minuten im Licht der Stra\u00dfenlaterne diesem ultraniedlichen Tierchen zu: ganz rund und h\u00f6chstens vier Zentimeter lang, mit gro\u00dfen, zarten \u00d6hrchen, gro\u00dfen Knopfaugen, langem, d\u00fcnnen Schwanz tat es M\u00e4uschendinge &#8211; schnupperte, huschte, guckte. Hachz.<\/p>\n<p>6. Geschenk<br \/>\nUnd DANN sah ich beim Kreuzen des Kaiser-Ludwig-Platzes auch noch einen Nikolaus: In Wei\u00df, mit Bischofsm\u00fctze, halb gef\u00fcllten Sack \u00fcber der Schulter &#8211; vielleicht der mietbare Pfarrei-Nikolaus?<\/p>\n<p>Herrn Kaltmamsell holte ich nur ab: Wir gingen zum Abendessen auf den (wegen Baustelle reduzierten) Christkindlmarkt am Sendlinger Tor, es gab Regensburger spezial (gut &#8211; f\u00fcr die Chronik: 5 Euro) und dann Pommes (mittelgut &#8211; 4 Euro). Daheim zum Nachtisch Fr\u00fcchtebrot und Schokolade.<\/p>\n<p>Am Montag waren meine Sch\u00f6ffinnentermine f\u00fcr 2023 eingetroffen: Ich hatte es nicht geschafft, beide f\u00fcr das Jahr geplante Urlaube bereits zu buchen, um bei eventuellen Kollisionen meine Verhinderung belegen zu k\u00f6nnen. Gl\u00fcck gehabt (noch ein Geschenk): Der Gro\u00dffamilienurlaub \u00fcber die Osterferien ist nicht betroffen.<\/p>\n<p>\u00a7<\/p>\n<p>Nach der Lekt\u00fcre eines Artikel im <i>Guardian<\/i> \u00fcber geraubte Kunstsch\u00e4tze aus der Antike gibt ein Mann 19 Antiquit\u00e4ten, die er &#8211; ohne Nachweis rechtm\u00e4\u00dfigen Erwerbs &#8211; von seiner Gro\u00dfmutter geerbt hat, an die Ursprungsl\u00e4nder zur\u00fcck.<br \/>\n<a href=\"https:\/\/www.theguardian.com\/culture\/2022\/nov\/11\/man-repatriates-19-antiquities-after-reading-guardian-article\" rel=\"noopener\" target=\"_blank\">&#8220;Man repatriates 19 antiquities after reading Guardian article&#8221;.<\/a><\/p>\n<p>Gelernt: Dazu muss man erst mal jemanden finden, der die Ursprungsl\u00e4nder benennen kann, und dann geht man damit zur jeweiligen Botschaft.<\/p>\n<p>\u00a7<\/p>\n<p>Swissmiss hat handgemalte Plakate fotografiert, <a href=\"https:\/\/www.swiss-miss.com\/2022\/11\/nyc-marathon-signs.html\" rel=\"noopener\" target=\"_blank\">die am Rand des New-York-Marathons hochgehalten wurden.<\/a> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg08.met.vgwort.de\/na\/0ad5cd3c368241d1b0bdf33acfc11ce8\" width=\"1\" height=\"1\" alt=\"\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. Geschenk Als ich Herrn Kaltmamsell am Montagmorgen bei Verlassen der Wohnung darauf hinwies, dass am Dienstag FEI Nikolaus sei, nannte er das &#8220;geradezu beleidigend&#8221;. Ich wollte lediglich ganz sicher gehen, dass sich gestern Morgen niemand w\u00fcrde gr\u00e4men m\u00fcssen, weil er vergessen hatte, mir einen Schokoladennikolaus vor die T\u00fcr zu stellen. Komplett gr\u00e4mungsfreier Morgen, zwei [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,2,1],"tags":[],"class_list":["post-82451","post","type-post","status-publish","format-standard","hentry","category-essen","category-fotos","category-general"],"_links":{"self":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/82451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/comments?post=82451"}],"version-history":[{"count":3,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/82451\/revisions"}],"predecessor-version":[{"id":82493,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/posts\/82451\/revisions\/82493"}],"wp:attachment":[{"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/media?parent=82451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/categories?post=82451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vorspeisenplatte.de\/speisen\/wp-json\/wp\/v2\/tags?post=82451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}